{"id":39767,"date":"2024-10-28T15:38:57","date_gmt":"2024-10-28T14:38:57","guid":{"rendered":"https:\/\/palmerini.net\/blog\/?p=39767"},"modified":"2024-10-28T15:38:58","modified_gmt":"2024-10-28T14:38:58","slug":"la-mentalita-governativa-romana-e-fallimentare-da-millenni","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/la-mentalita-governativa-romana-e-fallimentare-da-millenni\/","title":{"rendered":"La mentalit\u00e0 governativa romana \u00e8 fallimentare da millenni"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-39767\" data-postid=\"39767\" class=\"themify_builder_content themify_builder_content-39767 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_hnxi952 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_rkom954 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_d1ha217   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>Hai presente la storia dell\u2019invenzione del Personal Computer in uno sconosciuto garage degli Stati Uniti ? Ci si rende conto che \u00e8 una storiella ridicola se appena appena si si va a vedere quali problematiche tecniche ci furono per la realizzazione di quello vero, <a href=\"https:\/\/amzn.to\/3UONOVh\">il P 101<\/a>, a cui torner\u00f2 alla fine del testo. .<\/p><p>La<a href=\"https:\/\/amzn.to\/3YFB6dH\"> storiella del garage<\/a> \u00e8 servita a riempire l&#8217;immaginario popolare e creare un mito pubblicitario\u00a0 attorno ai fasulli protagonisti della stessa in modo che si comprasse il prodotto.\u00a0 <\/p><p>Questi miti servono ai potenti per dare un senso ai popolani, per far loro credere che l&#8217;attuale situazione sia in qualche modo dovuta ad eventi straordinari e magici che non serve indagare oltre.<\/p><p>Per esempio, qualcuno crede ancora che<a href=\"https:\/\/amzn.to\/3BZLTXc\"> 1000 persone male armate e mal equipaggiate, una armata Brancaleone,\u00a0 <\/a>per davvero invasero e conquistarono la Sicilia che invece era protetta da migliaia di soldati professionisti di tutto punto equipaggiati? <\/p><p>Questi miti per altro nascondono spesso una realt\u00e0 ben diversa fatta di tanti talenti sprecati per l&#8217;ignavia e la\u00a0 stupida cupidigia delle classi dirigenti.<\/p><p>In particolare, ecco cosa pensava il mitico <a href=\"https:\/\/amzn.to\/4fmcU5r\">Camillo Olivetti, fondatore della Olivetti<\/a>, della mentalit\u00e0 governativa romana e della stessa storia di Roma.<br \/><br \/>\u00abL&#8217;istruzione della nostra borghesia ha un fondamento prettamente anti-industriale. Noi siamo ancora i figli dei latini, che lasciarono ai servi e ai liberti i lavori industriali e che in ben poco conto li ritennero, tanto che ci tramandarono le storie dei pi\u00f9 mediocri proconsoli, e dei poetucoli e degli istrioni che dilettarono la decadenza romana, ma non ci ricordarono neppure i nomi di quei sommi ingegneri che costruirono le strade, gli acquedotti e i grandi monumenti dell&#8217;Impero Romano\u00bb.\u00a0\u00a0 \u00a0<br \/><br \/>Insomma la grandezza ingegneristica di Roma non \u00e8 stata dovuta ai governati o ai liberi, ma ai loro servi e schiavi.<br \/>La classe dirigente romana \u00e8 sempre stata predatrice di risorse umane e tecnologiche, e annientatrice dei popoli e dei talenti umani, e con il tempo questo porta inevitabilmente ad una classe dirigente senza alcuna qualit\u00e0, incapace, inetta, situazione che inevitabilmente conduce alla decadenza e cos\u00ec si arriv\u00f2 alla fine dell&#8217;impero, o meglio, alla sua divisione.<br \/><br \/>Infatti non fu decadente la classe dirigente dell&#8217;<a href=\"https:\/\/amzn.to\/3NIUfVN\">Impero romano d&#8217;oriente con capitale Costantinopoli<\/a>, ai quali siamo invece molto debitori come dir\u00f2 fra poco.\u00a0 I tanto calunniati bizantini avevano ricostruito il modo di essere della grecit\u00e0 classica, e parlavano greco, ma facendo tesoro dell&#8217;essere romani e cristiani. In questa\u00a0 veste per secoli furono ottimi amministratori ed ottimi ingegneri, ma anche ottimi politici, riuscendo a contrastare per secoli l&#8217;onda islamica provocata da Maometto. I bizantini seppero alleare anche gli slavi, per cristianizzarli\u00a0 tradussero le scritture ben 1200 anni prima che il Concilio vaticano II lo approvasse, e per farlo inventarono un alfabeto (il cirillico) adatto alle loro lingue.<\/p><p>E allora perch\u00e9 \u00e8 caduto quel meraviglioso impero? Certamente anche per una serie di lotte interne di potere in puro stile romano, ma soprattutto perch\u00e9 l&#8217;occidente l&#8217;ha lasciato solo a combattere l&#8217;espansionismo militare\u00a0islamico , e lo ha fatto perch\u00e9 in cambio dell&#8217;aiuto militare l&#8217;Occidente pretendeva\u00a0 la sottomissione politica e religiosa che Costantinopoli non accett\u00f2 sostanzialmente mai.<\/p><p>In un certo qual modo siamo ancora in questa situazione: l&#8217;Occidente pretende ancora l&#8217;adesione al proprio modello e la sottomissione al suo governo, e se non lo si accetta lascia che la guerra distrugga i renitenti, ed in vero la provoca.\u00a0 <\/p><p>L&#8217;intera classe dirigente occidentale \u00e8 evidentemente ancora come quella romana, ed infatti \u00e8 oramai incapace di risolvere un qualunque problema, e si affida, fintanto che pu\u00f2, alla distruzione, alla guerra. <\/p><p>La classe dirigente Cinese sta invece perseguendo una via di silenziosa costruzione del potere tramite la formazione continua, la competenza tecnica e giuridica della sua classe dirigente, attentamente formata. Per esempio, un ambasciatore cinese diventa tale solo dopo aver studiato per molti anni la storia, la cultura, la lingua e le politiche del paese dove operer\u00e0. E nel frattempo la Cina sforna ogni anno decine di milioni di ingegneri che arrivano non solo a convertire il deserto in terra fertile, ma anche a mandare in orbita un satellite per telecomunicazioni quantistiche che gli occidentali non sanno nemmeno cosa sono.<br \/><br \/>La Russia \u00e8 oggi l&#8217;erede dell&#8217;Impero Romano d&#8217;oriente, non solo culturalmente ma anche religiosamente. E quell&#8217;impero era necessariamente tollerante come per un breve periodo lo fu Roma. Stiamo quindi parlando di una potenza riemergente, con una lunga storia, che addirittura possiamo far risalire all&#8217;Impero Romano, ma quello buono.\u00a0 Ed infatti l\u2019alleanza economica, politica e di fatto anche militare dei BRICS \u00e8 patrocinata dalla Russia, che oggi conta una dirigenza diplomatica che non si vedeva da secoli .<br \/><br \/>Quella volta che l&#8217;impero Romano d&#8217;oriente fu invaso dall&#8217;Islam, per l&#8217;occidente fu una fortuna, perch\u00e9 numerosi furono le personalit\u00e0 di spicco che\u00a0 dovettero fuggire in occidente per poter continuare ad essere loro stessi. Fu questo che\u00a0 diede la stura a una rinascita dell&#8217;occidente, rinascita che conta pur anche\u00a0 grandi drammi come la schiavit\u00f9, il colonialismo e le grandi guerre, ma lo hanno portato comunque a diventare la civilt\u00e0 di riferimento per l&#8217;intero pianeta.<\/p><p>All&#8217;interno dell&#8217;occidente c&#8217;era invero una civilt\u00e0 <i>intermedia,<\/i> che per circa un millennio riusc\u00ec a barcamenarsi molto bene transitando il meglio di tutti fra i vari mondi, fino ad ergersi a nuovo paradigma e faro di civilt\u00e0, ed era Venezia, ma anch&#8217;essa fin\u00ec col soccombere alla violenza e al furto del nuovo rappresentante della mentalit\u00e0 romana d&#8217;occidente, Napoleone.<\/p><p><br \/>Di nuovo, purtroppo la classe dirigente occidentale negli ultimi decenni si \u00e8 corrotta, non solo perch\u00e9 sempre pi\u00f9 chiusa nei suoi tipici giochi di potere, non solo perch\u00e9 sempre pi\u00f9 incapace\u00a0 di esprimere efficienza (vogliamo ricordare, solo per ridere, la storia dei banchi a rotelle, oppure, per piangere, la storia dei vaccini della Presidente UE?), ma soprattutto perch\u00e9 essa \u00e8 oggi dominata dalle orrende piaghe della pedofilia e del satanismo.<br \/><br \/>Sulla pedofilia purtroppo i documenti ufficiali di ONU, OMS e Unione Europea propongono esplicitamente la sessualizzazione dei bambini gi\u00e0\u00a0 a 3-4 anni, e l\u2019insegnamento della masturbazione reciproca ai bambini di 9 con tanto di visione pornografica online, in pratica \u00e8 lo sdoganamento della pedofilia e della perversione a tutti i livelli. Ed d&#8217;altra parte anche la chiesa romana soffre gravemente di questo male, che porta perfino alla richiesta di fallimento alcune diocesi per poter salvare qualcosa dei beni che altrimenti andrebbero in risarcimento ai danneggiati. Su questo \u00e8 bene ricordare che la Repubblica di Venezia invece bruciava ogni opera creata dai pedofili e cancellava i loro nomi anche dai registri di nascita , come non fossero degni di essere considerati umani.<br \/><br \/><\/p><p>Sul satanismo, l&#8217;occidente \u00e8 governato da un sistema cabalistico satanico che oramai si mostra platealmente attraverso riti pubblici del toro presentati come eventi giocosi. L&#8217;iconografia satanista in realt\u00e0 si accompagna a orrende pratiche come sono emerse dal caso Epstein e ora dalle festine <a href=\"https:\/\/duckduckgo.com\/?q=%22Diddy+party%22&amp;t=vivaldi&amp;ia=web\">&#8220;Diddy party&#8221;<\/a> , con tanto di profusione di olio lubrificanti per i bambini&#8230;&#8230;. e c&#8217;\u00e8 gi\u00e0 all&#8217;orizzonte di molto peggio, perch\u00e9 il satanismo non riconosce dignit\u00e0 all&#8217;essere umano fino a considerarlo perfino un semplice cibo.<\/p><p>Ma come \u00e8 possibile oggi credere che qualcuna delle altre grandi potenze voglia sottomettersi a quella che \u00e8 una classe dirigente per altro\u00a0 pervertita nei valori, ed \u00e8 chiaro che gli altri imperi preferiscano la guerra ad una tale morte etica e spirituale che pure morte fisica e chimica da droghe e farmaci.\u00a0 \u00a0<\/p><p>Comprendo che\u00a0 queste cose fanno talmente schifo che turbano anche il solo leggerle,\u00a0 inoltre il\u00a0 punto di vista che ho espresso \u00e8 triste e crepuscolare, sembra senza speranza, e non \u00e8 nemmeno la prima volta che lo esprimo. Ma serve per cercare soluioni, che saranno efficaci solo se si conosce bene il problema.<\/p><p>Nel <a href=\"https:\/\/amzn.to\/3UONOVh\">libro di Giorgio Perotto che racconta la storia del primo PC della storia, il P 101<\/a>, realizzato da lui e altri nel laboratorio Olivetti, ho letto quel pensiero di Camillo Olivetti che ci dice che anche in quel tempo pure fra i migliori dell&#8217;unit\u00e0 d&#8217;Italia la classe dirigente italiana non era all&#8217;altezza dell&#8217;Italia, ed era sostanzialmente ancora quella Romana d&#8217;Occidente: non solo non capiva nulla di quanto stava avvenendo nello sviluppo tecnologico, ma era anche in realt\u00e0 serva del business alleato che fece in modo che quella tecnologia venisse bloccata in Italia e spostata negli USA. A conferma di questa regia occulta potremmo anche ricordarci della <a href=\"https:\/\/www.youtube.com\/watch?v=VteR-jMfWNM\">invenzione del &#8220;common rail&#8221;<\/a> ,\u00a0 come di molte altre tecnologie fatte sparire. <\/p><p>Nel libro Perotto ci fa gi\u00e0 capire cosa si dovrebbe fare per risollevare l&#8217;occidente, ossia fare come Olivetti e sostituire le persone della\u00a0 classe dirigente con personalit\u00e0 competenti che si danno da fare per raggiungere gli obbiettivi in maniera attenta al rispetto altrui. E ci metto anche l&#8217;ambiente.\u00a0 Ma poi ci sono gli altri successivi <a href=\"https:\/\/amzn.to\/4e78CxT\">libri di Perotto<\/a> che esplicitano il tema.<\/p><p>Tuttavia questo non \u00e8 possibile perch\u00e9, come ho dimostrato tante volte, le elezioni sono truccate e sostanzialmente inutili.<\/p><p>Dunque ci tocca restare con\u00a0 il modello di governo occidentale \u00e8 ancora con la mentalit\u00e0 di quello romano occidentale <a href=\"https:\/\/palmerini.net\/blog\/quando-le-venezie-divennero-un-stato-democratico\/\">da cui noi Veneti c&#8217;eravamo distaccati fin dalla caduta dell&#8217;Impero<\/a>, e che abbiamo <a href=\"https:\/\/amzn.to\/4hmyU1Q\">saputo portare all&#8217;apice con il nostro Stato Preunitario<\/a>.\u00a0 Basti sapere che <a href=\"https:\/\/palmerini.net\/blog\/quando-le-venezie-divennero-un-stato-democratico\/\">le prime elezioni democratiche universali si svolsero nelle isole della laguna gi\u00e0 nel seicento D.C<\/a>,\u00a0 cio\u00e8 nel VII secolo e non nel 1946 .<\/p><p>Cambiare l&#8217;occidente ora \u00e8 impossibile, <a href=\"https:\/\/amzn.to\/3NGfiIm\">la bestia \u00e8 all&#8217;angolo <\/a>gi\u00e0 da mesi dico che per sopravvivere cercher\u00e0 la guerra atomica.<\/p><p>Noi per ricominciare a vivere saremo costretti\u00a0 a ricreare gli stati preunitari.\u00a0 \u00a0 \u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Hai presente la storia dell\u2019invenzione del Personal Computer in uno sconosciuto garage degli Stati Uniti ? Ci si rende conto che \u00e8 una storiella ridicola se appena appena si si va a vedere quali problematiche tecniche ci furono per la realizzazione di quello vero, il P 101, a cui torner\u00f2 alla fine del testo. . [&hellip;]<\/p>\n","protected":false},"author":293,"featured_media":39768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12,5,6,61,11],"tags":[417,420,421,419,207,422,418],"class_list":["post-39767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autogoverno-popolo-veneto","category-cultura","category-politica","category-storia","category-venetie","tag-bisanzio","tag-perotto","tag-personal-computer","tag-roma","tag-scienza","tag-storia","tag-venezia","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2024\/10\/p101.jpg","jetpack-related-posts":[{"id":38787,"url":"https:\/\/palmerini.net\/blog\/cosa-faccio-adesso\/","url_meta":{"origin":39767,"position":0},"title":"Cosa faccio adesso","author":"Loris","date":"13 Maggio 2007","format":false,"excerpt":"","rel":"","context":"In &quot;Personale&quot;","block_context":{"text":"Personale","link":"https:\/\/palmerini.net\/blog\/category\/personale\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"<p>Hai presente la storia dell\u2019invenzione del Personal Computer in uno sconosciuto garage degli Stati Uniti ? Ci si rende conto che \u00e8 una storiella ridicola se appena appena si si va a vedere quali problematiche tecniche ci furono per la realizzazione di quello vero, <a href=\"https:\/\/amzn.to\/3UONOVh\">il P 101<\/a>, a cui torner\u00f2 alla fine del testo. .<\/p><p>La<a href=\"https:\/\/amzn.to\/3YFB6dH\"> storiella del garage<\/a> \u00e8 servita a riempire l'immaginario popolare e creare un mito pubblicitario\u00a0 attorno ai fasulli protagonisti della stessa in modo che si comprasse il prodotto.\u00a0 <\/p><p>Questi miti servono ai potenti per dare un senso ai popolani, per far loro credere che l'attuale situazione sia in qualche modo dovuta ad eventi straordinari e magici che non serve indagare oltre.<\/p><p>Per esempio, qualcuno crede ancora che<a href=\"https:\/\/amzn.to\/3BZLTXc\"> 1000 persone male armate e mal equipaggiate, una armata Brancaleone,\u00a0 <\/a>per davvero invasero e conquistarono la Sicilia che invece era protetta da migliaia di soldati professionisti di tutto punto equipaggiati? <\/p><p>Questi miti per altro nascondono spesso una realt\u00e0 ben diversa fatta di tanti talenti sprecati per l'ignavia e la\u00a0 stupida cupidigia delle classi dirigenti.<\/p><p>In particolare, ecco cosa pensava il mitico <a href=\"https:\/\/amzn.to\/4fmcU5r\">Camillo Olivetti, fondatore della Olivetti<\/a>, della mentalit\u00e0 governativa romana e della stessa storia di Roma.<br \/><br \/>\u00abL'istruzione della nostra borghesia ha un fondamento prettamente anti-industriale. Noi siamo ancora i figli dei latini, che lasciarono ai servi e ai liberti i lavori industriali e che in ben poco conto li ritennero, tanto che ci tramandarono le storie dei pi\u00f9 mediocri proconsoli, e dei poetucoli e degli istrioni che dilettarono la decadenza romana, ma non ci ricordarono neppure i nomi di quei sommi ingegneri che costruirono le strade, gli acquedotti e i grandi monumenti dell'Impero Romano\u00bb.\u00a0\u00a0 \u00a0<br \/><br \/>Insomma la grandezza ingegneristica di Roma non \u00e8 stata dovuta ai governati o ai liberi, ma ai loro servi e schiavi.<br \/>La classe dirigente romana \u00e8 sempre stata predatrice di risorse umane e tecnologiche, e annientatrice dei popoli e dei talenti umani, e con il tempo questo porta inevitabilmente ad una classe dirigente senza alcuna qualit\u00e0, incapace, inetta, situazione che inevitabilmente conduce alla decadenza e cos\u00ec si arriv\u00f2 alla fine dell'impero, o meglio, alla sua divisione.<br \/><br \/>Infatti non fu decadente la classe dirigente dell'<a href=\"https:\/\/amzn.to\/3NIUfVN\">Impero romano d'oriente con capitale Costantinopoli<\/a>, ai quali siamo invece molto debitori come dir\u00f2 fra poco.\u00a0 I tanto calunniati bizantini avevano ricostruito il modo di essere della grecit\u00e0 classica, e parlavano greco, ma facendo tesoro dell'essere romani e cristiani. In questa\u00a0 veste per secoli furono ottimi amministratori ed ottimi ingegneri, ma anche ottimi politici, riuscendo a contrastare per secoli l'onda islamica provocata da Maometto. I bizantini seppero alleare anche gli slavi, per cristianizzarli\u00a0 tradussero le scritture ben 1200 anni prima che il Concilio vaticano II lo approvasse, e per farlo inventarono un alfabeto (il cirillico) adatto alle loro lingue.<\/p><p>E allora perch\u00e9 \u00e8 caduto quel meraviglioso impero? Certamente anche per una serie di lotte interne di potere in puro stile romano, ma soprattutto perch\u00e9 l'occidente l'ha lasciato solo a combattere l'espansionismo militare\u00a0islamico , e lo ha fatto perch\u00e9 in cambio dell'aiuto militare l'Occidente pretendeva\u00a0 la sottomissione politica e religiosa che Costantinopoli non accett\u00f2 sostanzialmente mai.<\/p><p>In un certo qual modo siamo ancora in questa situazione: l'Occidente pretende ancora l'adesione al proprio modello e la sottomissione al suo governo, e se non lo si accetta lascia che la guerra distrugga i renitenti, ed in vero la provoca.\u00a0 <\/p><p>L'intera classe dirigente occidentale \u00e8 evidentemente ancora come quella romana, ed infatti \u00e8 oramai incapace di risolvere un qualunque problema, e si affida, fintanto che pu\u00f2, alla distruzione, alla guerra. <\/p><p>La classe dirigente Cinese sta invece perseguendo una via di silenziosa costruzione del potere tramite la formazione continua, la competenza tecnica e giuridica della sua classe dirigente, attentamente formata. Per esempio, un ambasciatore cinese diventa tale solo dopo aver studiato per molti anni la storia, la cultura, la lingua e le politiche del paese dove operer\u00e0. E nel frattempo la Cina sforna ogni anno decine di milioni di ingegneri che arrivano non solo a convertire il deserto in terra fertile, ma anche a mandare in orbita un satellite per telecomunicazioni quantistiche che gli occidentali non sanno nemmeno cosa sono.<br \/><br \/>La Russia \u00e8 oggi l'erede dell'Impero Romano d'oriente, non solo culturalmente ma anche religiosamente. E quell'impero era necessariamente tollerante come per un breve periodo lo fu Roma. Stiamo quindi parlando di una potenza riemergente, con una lunga storia, che addirittura possiamo far risalire all'Impero Romano, ma quello buono.\u00a0 Ed infatti l\u2019alleanza economica, politica e di fatto anche militare dei BRICS \u00e8 patrocinata dalla Russia, che oggi conta una dirigenza diplomatica che non si vedeva da secoli .<br \/><br \/>Quella volta che l'impero Romano d'oriente fu invaso dall'Islam, per l'occidente fu una fortuna, perch\u00e9 numerosi furono le personalit\u00e0 di spicco che\u00a0 dovettero fuggire in occidente per poter continuare ad essere loro stessi. Fu questo che\u00a0 diede la stura a una rinascita dell'occidente, rinascita che conta pur anche\u00a0 grandi drammi come la schiavit\u00f9, il colonialismo e le grandi guerre, ma lo hanno portato comunque a diventare la civilt\u00e0 di riferimento per l'intero pianeta.<\/p><p>All'interno dell'occidente c'era invero una civilt\u00e0 <i>intermedia,<\/i> che per circa un millennio riusc\u00ec a barcamenarsi molto bene transitando il meglio di tutti fra i vari mondi, fino ad ergersi a nuovo paradigma e faro di civilt\u00e0, ed era Venezia, ma anch'essa fin\u00ec col soccombere alla violenza e al furto del nuovo rappresentante della mentalit\u00e0 romana d'occidente, Napoleone.<\/p><p><br \/>Di nuovo, purtroppo la classe dirigente occidentale negli ultimi decenni si \u00e8 corrotta, non solo perch\u00e9 sempre pi\u00f9 chiusa nei suoi tipici giochi di potere, non solo perch\u00e9 sempre pi\u00f9 incapace\u00a0 di esprimere efficienza (vogliamo ricordare, solo per ridere, la storia dei banchi a rotelle, oppure, per piangere, la storia dei vaccini della Presidente UE?), ma soprattutto perch\u00e9 essa \u00e8 oggi dominata dalle orrende piaghe della pedofilia e del satanismo.<br \/><br \/>Sulla pedofilia purtroppo i documenti ufficiali di ONU, OMS e Unione Europea propongono esplicitamente la sessualizzazione dei bambini gi\u00e0\u00a0 a 3-4 anni, e l\u2019insegnamento della masturbazione reciproca ai bambini di 9 con tanto di visione pornografica online, in pratica \u00e8 lo sdoganamento della pedofilia e della perversione a tutti i livelli. Ed d'altra parte anche la chiesa romana soffre gravemente di questo male, che porta perfino alla richiesta di fallimento alcune diocesi per poter salvare qualcosa dei beni che altrimenti andrebbero in risarcimento ai danneggiati. Su questo \u00e8 bene ricordare che la Repubblica di Venezia invece bruciava ogni opera creata dai pedofili e cancellava i loro nomi anche dai registri di nascita , come non fossero degni di essere considerati umani.<br \/><br \/><\/p><p>Sul satanismo, l'occidente \u00e8 governato da un sistema cabalistico satanico che oramai si mostra platealmente attraverso riti pubblici del toro presentati come eventi giocosi. L'iconografia satanista in realt\u00e0 si accompagna a orrende pratiche come sono emerse dal caso Epstein e ora dalle festine <a href=\"https:\/\/duckduckgo.com\/?q=%22Diddy+party%22&amp;t=vivaldi&amp;ia=web\">\"Diddy party\"<\/a> , con tanto di profusione di olio lubrificanti per i bambini....... e c'\u00e8 gi\u00e0 all'orizzonte di molto peggio, perch\u00e9 il satanismo non riconosce dignit\u00e0 all'essere umano fino a considerarlo perfino un semplice cibo.<\/p><p>Ma come \u00e8 possibile oggi credere che qualcuna delle altre grandi potenze voglia sottomettersi a quella che \u00e8 una classe dirigente per altro\u00a0 pervertita nei valori, ed \u00e8 chiaro che gli altri imperi preferiscano la guerra ad una tale morte etica e spirituale che pure morte fisica e chimica da droghe e farmaci.\u00a0 \u00a0<\/p><p>Comprendo che\u00a0 queste cose fanno talmente schifo che turbano anche il solo leggerle,\u00a0 inoltre il\u00a0 punto di vista che ho espresso \u00e8 triste e crepuscolare, sembra senza speranza, e non \u00e8 nemmeno la prima volta che lo esprimo. Ma serve per cercare soluioni, che saranno efficaci solo se si conosce bene il problema.<\/p><p>Nel <a href=\"https:\/\/amzn.to\/3UONOVh\">libro di Giorgio Perotto che racconta la storia del primo PC della storia, il P 101<\/a>, realizzato da lui e altri nel laboratorio Olivetti, ho letto quel pensiero di Camillo Olivetti che ci dice che anche in quel tempo pure fra i migliori dell'unit\u00e0 d'Italia la classe dirigente italiana non era all'altezza dell'Italia, ed era sostanzialmente ancora quella Romana d'Occidente: non solo non capiva nulla di quanto stava avvenendo nello sviluppo tecnologico, ma era anche in realt\u00e0 serva del business alleato che fece in modo che quella tecnologia venisse bloccata in Italia e spostata negli USA. A conferma di questa regia occulta potremmo anche ricordarci della <a href=\"https:\/\/www.youtube.com\/watch?v=VteR-jMfWNM\">invenzione del \"common rail\"<\/a> ,\u00a0 come di molte altre tecnologie fatte sparire. <\/p><p>Nel libro Perotto ci fa gi\u00e0 capire cosa si dovrebbe fare per risollevare l'occidente, ossia fare come Olivetti e sostituire le persone della\u00a0 classe dirigente con personalit\u00e0 competenti che si danno da fare per raggiungere gli obbiettivi in maniera attenta al rispetto altrui. E ci metto anche l'ambiente.\u00a0 Ma poi ci sono gli altri successivi <a href=\"https:\/\/amzn.to\/4e78CxT\">libri di Perotto<\/a> che esplicitano il tema.<\/p><p>Tuttavia questo non \u00e8 possibile perch\u00e9, come ho dimostrato tante volte, le elezioni sono truccate e sostanzialmente inutili.<\/p><p>Dunque ci tocca restare con\u00a0 il modello di governo occidentale \u00e8 ancora con la mentalit\u00e0 di quello romano occidentale <a href=\"https:\/\/palmerini.net\/blog\/quando-le-venezie-divennero-un-stato-democratico\/\">da cui noi Veneti c'eravamo distaccati fin dalla caduta dell'Impero<\/a>, e che abbiamo <a href=\"https:\/\/amzn.to\/4hmyU1Q\">saputo portare all'apice con il nostro Stato Preunitario<\/a>.\u00a0 Basti sapere che <a href=\"https:\/\/palmerini.net\/blog\/quando-le-venezie-divennero-un-stato-democratico\/\">le prime elezioni democratiche universali si svolsero nelle isole della laguna gi\u00e0 nel seicento D.C<\/a>,\u00a0 cio\u00e8 nel VII secolo e non nel 1946 .<\/p><p>Cambiare l'occidente ora \u00e8 impossibile, <a href=\"https:\/\/amzn.to\/3NGfiIm\">la bestia \u00e8 all'angolo <\/a>gi\u00e0 da mesi dico che per sopravvivere cercher\u00e0 la guerra atomica.<\/p><p>Noi per ricominciare a vivere saremo costretti\u00a0 a ricreare gli stati preunitari.\u00a0 \u00a0 \u00a0<\/p>","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/39767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=39767"}],"version-history":[{"count":2,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/39767\/revisions"}],"predecessor-version":[{"id":39770,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/39767\/revisions\/39770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media\/39768"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=39767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=39767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=39767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}