{"id":3876,"date":"2014-08-05T17:02:40","date_gmt":"2014-08-05T16:02:40","guid":{"rendered":"http:\/\/www.palmerini.net\/blog\/?p=3876"},"modified":"2015-03-30T02:45:07","modified_gmt":"2015-03-30T01:45:07","slug":"distingui-fra-i-vari-movimenti-indipendentisti","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/distingui-fra-i-vari-movimenti-indipendentisti\/","title":{"rendered":"Non capisci un accidenti dei vari movimenti indipendentisti ? Ecco un aiutino"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3880 alignleft\" src=\"http:\/\/www.palmerini.net\/blog\/wp-content\/uploads\/2014\/08\/troll-295x300.png\" alt=\"troll\" width=\"295\" height=\"300\" srcset=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2014\/08\/troll-295x300.png 295w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2014\/08\/troll-25x25.png 25w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2014\/08\/troll.png 498w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/>Qualcosa per capire l&#8217;\u00a0indipendenza veneta e i suoi vari movimenti?<\/p>\n<p>La prima cosa da sapere \u00e8 che da sempre l&#8217;Italia considera i Veneti dei tontoloni, o dei &#8220;mona&#8221;, che si possono prendere in giro nell&#8217;urna. Leggendo scoprirai che questo \u00e8 storicamente <strong>vero.\u00a0<\/strong>Non ti sorprendere se scoprirai di essere truffato nell&#8217;urna anche in futuro.<\/p>\n<p>E comunque\u00a0per\u00a0capire il sentimento dell&#8217;indipendenza veneta, dovresti conoscere un po di storia del popolo veneto, una storia millenaria, bellissima, quella di un popolo che esiste da 3500 anni. Qui ora noi parliamo di quello che sono i percorsi per tornare indipendenti, non di quelli che propongono l&#8217; autonomia, non \u00e8 l&#8217;obbiettivo di diventare \u00a0&#8220;federati&#8221; con l&#8217;Italia, ma proprio sovrani e indipendenti dall&#8217;Italia. Se ti manca questa idea e volont\u00e0, e la\u00a0coscienza storica per\u00a0capirlo, non serve a nulla che continui a leggere.<\/p>\n<p>Noi dell&#8217;Autogoverno del Popolo Veneto \u00a0abbiamo<!--more--> cominciato a esercitare la sovranit\u00e0 di popolo veneto fin dal 1999, rivendicando l&#8217;essere veneto di tutto il territorio da Bergamo a Udine, anche di quello friulano. Infatti i popolo sono tutelati nel diritto internazionale dal principio di \u00a0autodeterminazione dei popoli, riconosciuto anche\u00a0dalle leggi italiane vigenti art.2 L.n.340\/1971 e L.n.881\/1977. Queste sono le cose che ora i venetisti falsari ripetono, magari aggiungendo che prima del 2006 non si poteva parlarne, cosa appunto falsa. \u00a0Noi siamo stati i primi e siamo ancora gli unici che riconoscono al popolo veneto la sua storia e la sua lingua, cosa che i movimenti &#8220;indipendenti&#8221; non fanno, e ti propongono un &#8220;popolo veneto&#8221; senza storia che parla italiano e riconosce la sovranit\u00e0 italiana.<\/p>\n<p>Noi abbiamo richiesto il riconoscimento della sovranit\u00e0 con centinaia di denunce, ricorsi e petizioni, ma la bont\u00e0 legale del nostro percorso si \u00e8 \u00a0per\u00f2 scontrata con una amara realt\u00e0 definitivamente accertata \u00a0nel 2011: non solo il Governo italiano, ma perfino i pi\u00f9 alti giudici negano l&#8217;esistenza del popolo veneto e se ne fregano di queste loro leggi.<\/p>\n<p><a href=\"http:\/\/www.palmerini.net\/blog\/sentenza-popolo-veneto-solo-residenti-senza-sovranita-autogoverno-solo-elezioni-amministrative\/\">C&#8217;\u00e8 pure una sentenza del 2011 della Corte di Cassazione<\/a>. D&#8217;altra parte lo Stato Italiano non svolge pi\u00f9 elezioni democratiche fin dal 2006 (l<a href=\"http:\/\/www.cortecostituzionale.it\/actionSchedaPronuncia.do?anno=2014&amp;numero=1\">o dice una sentenza che per\u00f2 dichiara ugualmente legale il governo non eletto !<\/a>).<\/p>\n<p>In poche parole e detto in maniera semplice, tutti i discorsi che girano sull&#8217;idea che si possa fare un referendum per l&#8217;indipendenza del &#8220;popolo veneto&#8221; ottenuta tramite referendum istituzionale italiano sono privi di fondamento, e gi\u00e0 dimostrati tali da sentenza. Stiamo parlando di una serie di movimenti come :<br \/>\n&#8211; Stato Veneto (clone di quello originale) dell&#8217;avv. Selmo,<br \/>\n&#8211; Partito Nasionae Veneto poi scomparso<br \/>\n&#8211; Veneto Stato (confusione semantica)<br \/>\n&#8211; Indipendenza Veneta<br \/>\n&#8211; Veneti indipendenti<br \/>\n&#8211; altri cloni.<\/p>\n<p>Questi partiti servono solo per portare potere alle istituzioni italiane, per alcuni e per me sono una presa in giro per i venetisti.<\/p>\n<p>Per gli stessi motivi sono del tutto giuridicamente infondati tutti i percorsi che propongono l&#8217;indipendenza di una regione amministrativa italiana, perch\u00e9 nessun territorio regionale italiano \u00e8 abitato da un solo popolo, tranne le Isole, e questo non \u00e8 un caso , ma una cosa voluta e determinata per cancellare le identit\u00e0 storiche e millenarie.<\/p>\n<p>D&#8217;altra parte l&#8217;Italia considera da sempre i veneti dei &#8220;mone&#8221; che come allocchi ignoranti cadono nella trappola dei partiti e delle truffe elettorali, <a href=\"http:\/\/www.palmerini.net\/blog\/?s=1866\">e questo in effetti \u00e8 vero fin dal 1866!<\/a>\u00a0E pure il <a href=\"http:\/\/www.palmerini.net\/blog\/le-prove-che-il-referendum-del-1946-e-nullo\/\">referendum monarchia-repubblica del 1946<\/a> \u00e8 stato fatto senza la partecipazione\u00a0dei veneti di Istria, Dalmazia e Isole Adriatiche che avevano diritto legale di votare e di decidere di che stato far parte.<\/p>\n<p>Riflettiamo: presentandosi come &#8220;amico&#8221; o perfino0 parente \u00e8 pi\u00f9 facile derubare qualcuno, in realt\u00e0 molti finti partiti indipendentisti sono utili all&#8217;Italia e servono a derubare uno che ti crede suo amico.<\/p>\n<p>Per altro \u00e8 diventato del tutto evidente negli ultimi 2 anni che i governi del mondo se ne fregano del diritto dei popoli (e specie USA e UE, ma anche la Cina ) , salvo che non serva \u00a0ai loro interessi. Noi siamo in questa area di influenza, l&#8217;indipendenza del Popolo \u00a0Veneto non conviene all&#8217;Impero USA-UE , ed esplicitamente non danno riconoscimento del diritto di una etnia \u00a0o popolo \u00a0alle proprie istituzioni perfino quando il governo lo bombarda . Ricorda per\u00f2 che se parli italiano\u00a0\u00e8 molto difficile dire che non sei italiano.<\/p>\n<p>Per cui di fatto questi stati riconoscono solo il diritto di sovranit\u00e0 e integrit\u00e0 degli stati, come era 100 anni fa.<\/p>\n<p>Fortunatamente, con studi giuridici e storici, ho scoperto nel 2006\u00a0che il Lombardo-Veneto in realt\u00e0 fu invaso illegalmente, \u00a0nel 1859 \u00a0nella parte lombardia, e nel 1866 \u00a0nella parte venezia. Questo in violazione dei trattati e di quello stesso principio di sovranit\u00e0 ed indipendenza ed integrit\u00e0 degli stati che USA e UE oggi rivendicano come primario, per esempio in Ucraina.<\/p>\n<p>Il Lombardo-Veneto per altro \u00e8 lo stato legalmente &#8220;successorio&#8221; (erede legale) della Repubblica Veneta, a cui nel 1815 ven)nero accorpati i Ducati di Mantova e di Milano (nei siti sotto trovi il dettaglio di tutta la storia). Stiamo sempre parlando della sovranit\u00e0 veneta, ma allargata. Infatti mentre i Ducati di Milano e Mantova finirono giuridicamente &#8220;estinti&#8221;, la Repubblica Veneta cambi\u00f2 nome, e in un certo senso torn\u00f2 sovrana perch\u00e9 era stata &#8220;debellata&#8221; militarmente nel 1797 (cio\u00e9 resa del tutto incapace di difendersi militarmente), \u00a0quando questo fatto veniva considerato legale. In realt\u00e0 ancora nel 1945 la Germania venne &#8220;debellata&#8221; e per questo non fu nemmeno fatta sedere al tavolo del trattato di pace.<\/p>\n<p>Il Lombardo-Vento invece vinse la guerra, ma fu infiltrato dalla camorra italiana che si impadron\u00ec come un cancro delle Istituzioni , minacciando di morte chiunque si opponesse. Del tutto in maniera viscida e illegale, senza alcun onore.<\/p>\n<p>Noi stiamo \u00a0portando avanti non solo il diritto di autodeterminare proprie istituzioni che ha il popolo veneto, e solo esso, ma anche \u00a0il diritto di sovranit\u00e0 e indipendenza dello stato Lombardo-Veneto, ma in esso \u00a0abbiamo riconosciuto l&#8217;esistenza del popolo Veneto ma anche di quello Insubre (ducato di Milano) e Mantovano (Ducato di Mantova) .<\/p>\n<p>Quindi Veneti, Insubri, Mantovani, potenzialmente altre minoranze come Friulani e germanofoni, \u00a0potranno tornare indipendenti ma solo una volta \u00a0raggiunta l&#8217;indipendenza del Lombardo-Veneto.<\/p>\n<p>Abbiamo portato in tribunale gli studi sulla sovranit\u00e0 del Lombardo-Veneto, ottenendo nel 2008 il riconoscimento della possibile non sovranit\u00e0 dell&#8217;Italia sul territorio tramite <a href=\"http:\/\/www.palmerini.net\/blog\/la-prova-che-lo-stato-veneto-esiste-ed-e-sovrano\/\">una sentenza <\/a>. L&#8217;Italia non ha mai avuto sovranit\u00e0 legale sul territorio dello stato lombardo-veneto, e per altro l&#8217;annessione \u00e8 stata comunque annullata nel 2010, non per errore ma per nostre pressioni internazionali.<\/p>\n<p>In sostanza noi rivendichiamo il diritto alla &#8220;integrit\u00e0 territoriale&#8221; del Lombardo-Veneto che \u00e8 uno stato vittorioso in guerra (non &#8220;debellato&#8221; come la Repubblica Veneta), invaso illegalmente dal Piemonete e annesso dall&#8217;Italia con una frode (altri miei studi hanno dimostrato che il voto di annessione fu espresso dai soldati italiani). Tutto questo \u00e8 vietata dal diritto internazionale.<\/p>\n<p>Quindi non solo il referendum regionale &#8220;italiano&#8221; \u00e8 una bufala, ma lo sono:<br \/>\n&#8211; la via referendaria autogestita da soggetti autoproclamati e limitata alla regione veneto (plebiscito.eu)<br \/>\n&#8211; la rivendicazione della sovranit\u00e0 della repubblica veneta<br \/>\n&#8211; l&#8217;idea di una secessione legale tramite istituzioni e partiti che riconoscono la sovranit\u00e0 italiana<\/p>\n<p>In particolare l&#8217;ultimo punto: chi corre alle elezioni italiane senza dire che l&#8217;Italia \u00e8 illegale fin dall&#8217;inizio sta facendo il lavoro di &#8220;legittimare&#8221; l&#8217;Italia e quindi costruisce un muro che impedisce l&#8217;indipendenza, perch\u00e9 se l&#8217;Italia \u00e8 legale la sua costituzione vieta l&#8217;indipendenza. Non esiste una legge, per gli attuali USA e UE, che permetta di scavalcare la Costituzione.<\/p>\n<p>Quindi i &#8220;referendum&#8221; sono tutte bufale giuridicamente e praticamente infondate, deleterie perch\u00e9 di fatto negano la sovranit\u00e0 sul territorio dello stato legale Lombardo-Veneto, mentre rivendicare la falsa annessione dell&#8217;Italia e la sovranit\u00e0 del Lombardo-Veneto \u00e8 l&#8217; unica via oggi giuridicamente riconosciuta valida a livello internazionale.<\/p>\n<p>La dimostrazione &#8220;esterna&#8221; te la danno questi fatti:<br \/>\n&#8211; alla Catalonia viene negato il referendum , non \u00e8 mai esistita come stato tal quale \u00e8 oggi<br \/>\n&#8211; alla Scozia \u00e8 stato concesso il referendum, infatti era uno stato e il governo inglese lo ha sempre saputo<br \/>\n&#8211; alle ex-repubbliche Jugoslave \u00e8 stata riconosciuta la sovranit\u00e0 perch\u00e9 erano stati esistenti prima della Jugoslavia<br \/>\n&#8211; lo status del Kossovo non \u00e8 ancora chiaro, pochi stati lo riconoscono sovrano, non la stessa Serbia e tutto questo dopo una sanguinosa guerra che ha visto accorrere i caschi blu dell&#8217;ONU (cosa che sembra succedere solo quando ci sono interessi petroliferi)<\/p>\n<p>Ti invito a vedere questi siti<br \/>\nwww.statoveneto.net<br \/>\nwww.lombardo-veneto.net<br \/>\ne a darti da fare se vuoi liberarti dallo stato che da sempre impoverisce Veneti, Lombardi e Mantovani.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qualcosa per capire l&#8217;\u00a0indipendenza veneta e i suoi vari movimenti? La prima cosa da sapere \u00e8 che da sempre l&#8217;Italia considera i Veneti dei tontoloni, o dei &#8220;mona&#8221;, che si possono prendere in giro nell&#8217;urna. Leggendo scoprirai che questo \u00e8 storicamente vero.\u00a0Non ti sorprendere se scoprirai di essere truffato nell&#8217;urna anche in futuro. E comunque\u00a0per\u00a0capire [&hellip;]<\/p>\n","protected":false},"author":292,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12,10,15,90,135,1,6,61],"tags":[],"class_list":["post-3876","post","type-post","status-publish","format-standard","hentry","category-autogoverno-popolo-veneto","category-diritti-umani","category-giustizia","category-lingua-veneta","category-lombven","category-personale","category-politica","category-storia","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/3876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/292"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=3876"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/3876\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=3876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=3876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=3876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}