{"id":37478,"date":"2022-02-23T15:32:42","date_gmt":"2022-02-23T14:32:42","guid":{"rendered":"https:\/\/palmerini.net\/blog\/?p=37478"},"modified":"2022-02-23T15:32:44","modified_gmt":"2022-02-23T14:32:44","slug":"la-vitamina-c-migliora-la-prognosi-dei-malati-gravi-di-covid-19","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/la-vitamina-c-migliora-la-prognosi-dei-malati-gravi-di-covid-19\/","title":{"rendered":"La Vitamina C migliora la prognosi dei malati gravi di Covid-19"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-37478\" data-postid=\"37478\" class=\"themify_builder_content themify_builder_content-37478 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_5o1g939 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_monp940 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_nguk151   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-31801\" src=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r.jpg 300w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r-1024x682.jpg 1024w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r-1160x773.jpg 1160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nel dicembre 2021 sono stati pubblicati i risultati di <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34975830\/\" target=\"_blank\" rel=\"noopener\">uno studio clinico iraniano condotto su 120 pazienti ospedalizzati malati critici infettati con COVID-19<\/a>.\u00a0<\/p><p>Gi\u00e0 in precedenza la vitamina C \u00e8 stata indicata come benefica per i pazienti con malattia da coronavirus 2019 (COVID-19).<\/p><p>Un gruppo di 31 pazienti ha ricevuto una capsula di 500 mg di vitamina C al giorno per 14 giorni. Un gruppo di controllo di 69 pazienti ha ricevuto la stessa alimentazione ma senza integrazione di vitamina C.<\/p><p>Dopo le 2 settimane \u00e8 stata effettuata la misurazione dei parametri patologici e biochimici, e si sono riscontrati livello di K nel siero significativamente pi\u00f9 bassi nei pazienti con integrazione rispetto al gruppo di controllo (3,93 vs 4,21 mEq\/L, p &lt; 0,01).<\/p><p>La supplementazione di vitamina C ha portato a una durata media di sopravvivenza pi\u00f9 alta rispetto a quella del gruppo di controllo (8 vs. 4 giorni, p &lt; 0,01). C&#8217;era un&#8217;associazione lineare tra il numero di giorni di assunzione di vitamina C e la durata della sopravvivenza (B = 1,66, p &lt; 0,001).<\/p><p>L&#8217;integrazione di vitamina C non ha avuto alcun effetto sulla glicemia, sulla pressione arteriosa media, sui parametri dei gas sanguigni arteriosi (ABG), sulla Scala Glasgow di Coma (GCS), sulla funzione renale, sull&#8217;emocromo (CBC), sull&#8217;emoglobina (Hb), sulle piastrine (Plt), sul tempo di tromboplastina parziale (PTT), sull&#8217;albumina, sull&#8217;ematocrito (Hct), e su altri elettroliti del siero tra cui sodio (Na), calcio e fosforo (P).<\/p><p>Lo studio ha quindi dimostrato il potenziale della integrazione di vitamina C nel migliorare la durata della sopravvivenza dei pazienti critici con COVID-19.<\/p><p>Nel frattempo il Governo italiano continua con il deleterio e mortale protocollo della &#8220;Tachipirina e Vigile Attesa &#8220;: strage su commissione ?<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Nel dicembre 2021 sono stati pubblicati i risultati di uno studio clinico iraniano condotto su 120 pazienti ospedalizzati malati critici infettati con COVID-19.? Gi? in precedenza la vitamina C ? stata indicata come benefica per i pazienti con malattia da coronavirus 2019 (COVID-19). Un gruppo di 31 pazienti ha ricevuto una capsula di 500 mg [&hellip;]<\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[325,324,4],"tags":[318,323,317],"class_list":["post-37478","post","type-post","status-publish","format-standard","hentry","category-medica","category-medicina","category-scienza","tag-acido-ascorbico","tag-cura-covid-19","tag-vitamina-c","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r.jpg 300w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r-1024x682.jpg 1024w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2020\/06\/acido-ascorbico-r-1160x773.jpg 1160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nel dicembre 2021 sono stati pubblicati i risultati di <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34975830\/\" target=\"_blank\" rel=\"noopener\">uno studio clinico iraniano condotto su 120 pazienti ospedalizzati malati critici infettati con COVID-19<\/a>.\u00a0<\/p><p>Gi\u00e0 in precedenza la vitamina C \u00e8 stata indicata come benefica per i pazienti con malattia da coronavirus 2019 (COVID-19).<\/p><p>Un gruppo di 31 pazienti ha ricevuto una capsula di 500 mg di vitamina C al giorno per 14 giorni. Un gruppo di controllo di 69 pazienti ha ricevuto la stessa alimentazione ma senza integrazione di vitamina C.<\/p><p>Dopo le 2 settimane \u00e8 stata effettuata la misurazione dei parametri patologici e biochimici, e si sono riscontrati livello di K nel siero significativamente pi\u00f9 bassi nei pazienti con integrazione rispetto al gruppo di controllo (3,93 vs 4,21 mEq\/L, p &lt; 0,01).<\/p><p>La supplementazione di vitamina C ha portato a una durata media di sopravvivenza pi\u00f9 alta rispetto a quella del gruppo di controllo (8 vs. 4 giorni, p &lt; 0,01). C'era un'associazione lineare tra il numero di giorni di assunzione di vitamina C e la durata della sopravvivenza (B = 1,66, p &lt; 0,001).<\/p><p>L'integrazione di vitamina C non ha avuto alcun effetto sulla glicemia, sulla pressione arteriosa media, sui parametri dei gas sanguigni arteriosi (ABG), sulla Scala Glasgow di Coma (GCS), sulla funzione renale, sull'emocromo (CBC), sull'emoglobina (Hb), sulle piastrine (Plt), sul tempo di tromboplastina parziale (PTT), sull'albumina, sull'ematocrito (Hct), e su altri elettroliti del siero tra cui sodio (Na), calcio e fosforo (P).<\/p><p>Lo studio ha quindi dimostrato il potenziale della integrazione di vitamina C nel migliorare la durata della sopravvivenza dei pazienti critici con COVID-19.<\/p><p>Nel frattempo il Governo italiano continua con il deleterio e mortale protocollo della \"Tachipirina e Vigile Attesa \": strage su commissione ?<\/p>","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/37478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=37478"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/37478\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=37478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=37478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=37478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}