{"id":3084,"date":"2013-11-04T17:58:27","date_gmt":"2013-11-04T16:58:27","guid":{"rendered":"http:\/\/www.palmerini.net\/blog\/?p=3084"},"modified":"2013-11-04T18:19:44","modified_gmt":"2013-11-04T17:19:44","slug":"il-parlamento-italiano-costa-3-volte-quello-inglese","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/il-parlamento-italiano-costa-3-volte-quello-inglese\/","title":{"rendered":"Il parlamento italiano costa 3 volte quello inglese.E falsifica i dati"},"content":{"rendered":"<p>L&#8217;Italia ha un parlamento diviso in Camera e Senato , per lo pi\u00f9 eletti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3086 alignright\" alt=\"aumento-costi-camera\" src=\"http:\/\/www.palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/aumento-costi-camera1-165x600.jpg\" width=\"165\" height=\"600\" srcset=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/aumento-costi-camera1-165x600.jpg 165w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/aumento-costi-camera1.jpg 280w\" sizes=\"auto, (max-width: 165px) 100vw, 165px\" \/><\/p>\n<p>La Camera ha 630 membri eletti, il Senato ha\u00a0\u00a0a 315 membri, di cui alcuni a vita, per un totale di 965 membri .<\/p>\n<p>L&#8217; Inghilterra ha una camera \u00a0(la Camera dei Comuni) con 650 membri eletti, e la camera dei Lord con 826 membri totali, di cui \u00a092 ereditari, mentre gli altri 709 sono membri a vita\u00a0 (alla faccia del principio di democrazia repubblicana). L&#8217;Inghilterra ha dunque 1476 parlamentari, \u00a0pari al 152% dei parlamentari, in pratica l&#8217;equivalente di una terza camera !<\/p>\n<p>Il quotidiano L&#8217;Adige ha pubblicato un articolo secondo cui la Camera dei Comuni inglese costa la met\u00e0 della Camera Italiana.<\/p>\n<p>La Camera ha sostenuto di aver ridotto i costi, ma secondo l&#8217;articolista la realt\u00e0 \u00e8 ben diversa, e c&#8217;\u00e8 stato un aumento della spesa di ben oltre il 10% .<\/p>\n<p>Da questo si capisce che la Camera mente sui dati comunicati al cittadino! E si capisce che \u00a0la riduzione dei parlamentari non \u00e8 finalizzata a ridurre le spese, ma \u00e8 il tentativo del regime di ridurre ancora pi\u00f9 in poche mani il potere, e non risponde affatto a principi di risparmio.<\/p>\n<p>A lato l&#8217;articolo, sotto un video su quanto sono coglioni gli italiani che si privano di servizi alla collettivit\u00e0 per mantenere questa masnada di sprechi manigoldi.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/photo.php?v=10202331383075918\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3090 alignleft\" alt=\"video-facebook\" src=\"http:\/\/www.palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/video-facebook1-265x300.jpg\" width=\"265\" height=\"300\" srcset=\"https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/video-facebook1-265x300.jpg 265w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/video-facebook1-530x600.jpg 530w, https:\/\/palmerini.net\/blog\/wp-content\/uploads\/2013\/11\/video-facebook1.jpg 594w\" sizes=\"auto, (max-width: 265px) 100vw, 265px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Italia ha un parlamento diviso in Camera e Senato , per lo pi\u00f9 eletti. La Camera ha 630 membri eletti, il Senato ha\u00a0\u00a0a 315 membri, di cui alcuni a vita, per un totale di 965 membri . L&#8217; Inghilterra ha una camera \u00a0(la Camera dei Comuni) con 650 membri eletti, e la camera dei Lord [&hellip;]<\/p>\n","protected":false},"author":292,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,6],"tags":[],"class_list":["post-3084","post","type-post","status-publish","format-standard","hentry","category-economia","category-politica","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/3084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/292"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=3084"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/3084\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=3084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=3084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=3084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}