{"id":2766,"date":"2013-07-27T19:38:05","date_gmt":"2013-07-27T18:38:05","guid":{"rendered":"http:\/\/www.palmerini.net\/blog\/?p=2766"},"modified":"2013-10-09T17:18:22","modified_gmt":"2013-10-09T16:18:22","slug":"ecco-dove-il-referendum-consultivo-per-lindipendenza-del-veneto-e-in-violazione-dello-statuto-della-regione","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/ecco-dove-il-referendum-consultivo-per-lindipendenza-del-veneto-e-in-violazione-dello-statuto-della-regione\/","title":{"rendered":"Ecco dove il referendum consultivo per l&#8217;indipendenza del veneto \u00e8 in violazione dello statuto della regione"},"content":{"rendered":"<p><a href=\"http:\/\/statoveneto.net\/governo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2976 alignright\" alt=\"sovranita-thumb\" src=\"http:\/\/www.palmerini.net\/blog\/wp-content\/uploads\/2013\/10\/sovranita-thumb.png\" width=\"250\" height=\"242\" \/><\/a>Prima di leggere quanto segue, conviene sapere che il Referendum Consultivo per l&#8217;indipendenza del Veneto \u00e8 totalmente vietato dallo Statuto della Regione. Per fare il verso a certi giochi di parole, se si preferisce il referendum &#8220;non \u00e8 permesso&#8221; oppure, per continuare a giocare con le parole &#8220;\u00e8 esplicitamente espresso come non legittimo&#8221;. \u00a0Insomma la regione non lo pu\u00f2 indire .<\/p>\n<p>In questo specifico posto \u00e8 spiegato il perch\u00e9\u00a0<a href=\"http:\/\/www.palmerini.net\/blog\/lo-statuto-del-veneto-vieta-il-referendum-consultivo-sullindipendenza\/\">http:\/\/www.palmerini.net\/blog\/lo-statuto-del-veneto-vieta-il-referendum-consultivo-sullindipendenza\/<\/a><\/p>\n<p>Ammesso che quell&#8217;articolo non fosse sufficiente (ma stiamo andando gi\u00e0 su questioni teoriche) il referendum sarebbe comunque in contrasto con lo statuto su molti altri articoli.<\/p>\n<p>L&#8217;articolo 2.2 dello statuto della regione veneto fatto nel 2012 afferma che &#8220;La Regione salvaguarda e promuove l\u2019identit\u00e0 storica del popolo e della civilt\u00e0 veneta&#8221; .<\/p>\n<p>Indipendenza Veneta propone una consultazione non del popolo veneto secondo l&#8217;identit\u00e0 storica, ma ai soli attuali residenti del veneto, e se la regione lo approvasse sarebbe in violazione del suddetto articolo.<\/p>\n<p>Questa violazione da parte della regione sarebbe nulla rispetto alla violazione dell&#8217;articolo 3.1 che dice<\/p>\n<p>&#8220;Art. 3 &#8211; Autonomia della Regione del Veneto e degli enti locali.1. L\u2019autonomia della Regione si esprime nell\u2019esercizio della potest\u00e0 legislativa,regolamentare e amministrativa e nella piena attuazione della autonomia finanziaria riconosciuta dalla Costituzione&#8221;.<\/p>\n<p>E la Costituzione non assegna alcuna competenza alla regione per quanto riguarda la politica internazionale o estera, anzi la riserva allo stato per prima all&#8217;art.117 secondo comma che afferma &#8220;Lo Stato ha legislazione esclusiva nelle seguenti materie: a) politica estera e rapporti internazionali dello Stato; rapporti dello Stato con l&#8217;Unione europea; &#8221;<\/p>\n<p>Lo stesso articolo evidentemente rende palese che \u00e8 del tutto fantasioso pensare ad una relazione diretta da &#8220;stato&#8221; della regione (veneto) anche con l&#8217;Unione Europea.<\/p>\n<p>A tarpare le ali delle fantasie di Indipendenza Veneta basterebbe dare una letta anche del solo articolo 1 dello statuto che dice :<\/p>\n<p>&#8220;Art. 1 &#8211; La Regione del Veneto.1. Il Veneto \u00e8 Regione autonoma, secondo il presente Statuto, in armonia con la Costituzione della Repubblica&#8221;.<\/p>\n<p>Ancora, Art. 11.2. &#8220;La Regione informa la propria attivit\u00e0 al principio di responsabilit\u00e0 politica ed amministrativa dei diversi livelli di governo locale nonch\u00e9 al rispetto e alla valorizzazione dell\u2019autonomia dei comuni, delle loro unioni, delle province, delle citt\u00e0 metropolitane cos\u00ec come riconosciute dalla Costituzione&#8221; . Ossia non pu\u00f2 assegnare a questi enti funzioni fuori costituzione.<\/p>\n<p>Anche passasse un referendum indetto dalla regione questo darebbe al governo motivo di bloccare ogni cosa sotto il cappello dell<br \/>\nArt. 126 &#8220;Con decreto motivato del Presidente della Repubblica sono disposti lo scioglimento del Consiglio regionale e la rimozione del Presidente della Giunta che abbiano compiuto atti contrari alla Costituzione o gravi violazioni di legge. Lo scioglimento e la rimozione possono altres\u00ec essere disposti per ragioni di sicurezza nazionale. &#8221;<\/p>\n<p>Chi ha proposto il progetto di Indipendenza Veneta non conosce le basi elementari del diritto costituzionale italiano<\/p>\n<p>Io mi fermo qui perch\u00e9 sul tema ci ho scritto un libro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima di leggere quanto segue, conviene sapere che il Referendum Consultivo per l&#8217;indipendenza del Veneto \u00e8 totalmente vietato dallo Statuto della Regione. Per fare il verso a certi giochi di parole, se si preferisce il referendum &#8220;non \u00e8 permesso&#8221; oppure, per continuare a giocare con le parole &#8220;\u00e8 esplicitamente espresso come non legittimo&#8221;. \u00a0Insomma la [&hellip;]<\/p>\n","protected":false},"author":292,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12,10,15,6],"tags":[],"class_list":["post-2766","post","type-post","status-publish","format-standard","hentry","category-autogoverno-popolo-veneto","category-diritti-umani","category-giustizia","category-politica","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":4033,"url":"https:\/\/palmerini.net\/blog\/la-legge-naturale-non-e-una-legge\/","url_meta":{"origin":2766,"position":0},"title":"LA LEGGE NATURALE NON E&#8217; UNA LEGGE","author":"Loris","date":"9 Dicembre 2015","format":false,"excerpt":"Negli ultimi anni si assiste alla diffusione di alcune teorie che vedono nella totale libert\u00e0 dell'individuo il valore supremo da difendere. Sono teorie che sostanzialmente fanno parte di quella corrente di pensiero che viene definita \"libertaria\" o anche anarchica. Infatti per la Treccani \"libertario\" \u00e8 chi o che \"considera e\u2026","rel":"","context":"In &quot;Attualit\u00e0\u00a0 e storia del Popolo Veneto&quot;","block_context":{"text":"Attualit\u00e0\u00a0 e storia del Popolo Veneto","link":"https:\/\/palmerini.net\/blog\/category\/autogoverno-popolo-veneto\/"},"img":{"alt_text":"YEAREND PICTURES 2000 - Ruqia Aroo, 80, carries her malnourished grandson Khalif Sheikh Adan, 5, near the carcasses of her dead herd of cattle near Afder, 1100 kms south east of Addis Ababa, April 18, 2000. (CANADA OUT) gm\/Photo by George Mulala REUTERS","src":"https:\/\/i0.wp.com\/www.palmerini.net\/blog\/wp-content\/uploads\/2015\/12\/eritrea-siccita-300x212.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/2766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/292"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=2766"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/2766\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=2766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=2766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=2766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}