{"id":184,"date":"2008-03-12T17:49:38","date_gmt":"2008-03-12T16:49:38","guid":{"rendered":"http:\/\/www.palmerini.net\/blog\/?p=184"},"modified":"2008-03-12T17:51:58","modified_gmt":"2008-03-12T16:51:58","slug":"e-fosse-dimostrato-che-i-terroristi-sono-al-governo","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/e-fosse-dimostrato-che-i-terroristi-sono-al-governo\/","title":{"rendered":"E fosse dimostrato che i terroristi sono al governo ?"},"content":{"rendered":"<style type=\"text\/css\"><!-- \t\t@page { size: 21cm 29.7cm; margin: 2cm } \t\tP { margin-bottom: 0.21cm } \t--> \t<\/style>\n<p>Quale sarebbe la prima cosa che farebbe un gruppo terrorista e sovversivo che salisse al potere?<\/p>\n<p>Ovvio, quello che tutti i dittatori hanno sempre fatto, ossia: ABROGARE I REATI COMMESSI DA LORO STESSI.<\/p>\n<p>Sono molti anni che vado dicendo che c&#8217;\u00e8 stato un colpo di Stato in Italia, iniziato nel 1994, fatto da destra e sinistra insieme omertosamente. Nella mia ricerca della verit\u00e0 o intravisto anche legami con la mafia, con il terrorismo, con potentati economici. E siccome la mafia \u00e8 terrorismo (lo disse anche Falcone), ecco che i terroristi sarebbero al governo.<\/p>\n<p>Quello che \u00e8 certo \u00e8 che i reati che ho denunciato essere stati compiuti da lor signori sono stati tutti abrogati o sostituiti in modo da non poter essere processati. Esattamente come se la mafia fosse salita al governo<\/p>\n<p>Per esempio: avevo denunciato un sistema di filme false che serviva ad escludere i partiti concorrenti? I reati sono stati prima eliminati o ridotti ad ammenda, e ora le firme le raccolgono solo gli &#8220;altri&#8221;, in modo da non farli concorrere alle elezioni.<\/p>\n<p>Non solo, scopro che NON E&#8217; PIU&#8217; REATO modificare la Costituzione violando la Costituzione stessa perch\u00e9 l Art. 283 &#8211; &#8220;Attentato contro la costituzione dello Stato&#8221; che diceva &#8220;<em>Chiunque commette un fatto diretto a mutare la costituzione dello Stato, o la forma del Governo, con mezzi non consentiti dall&#8217;ordinamento costituzionale dello Stato, \u00e8 punito con la reclusione non inferiore a dodici anni.<\/em> &#8221; \u00e8 stato modificato in<\/p>\n<p><em>&#8220;Chiunque, con atti violenti, commette un fatto diretto e idoneo a mutare la Costituzione dello Stato o la forma di governo, \u00e8 punito con la reclusione non inferiore a cinque anni. &#8220;<\/em><\/p>\n<p>e quindi, se non fai violenza ma usi le TV per plagiare il popolo e ottenerne il consenso, se poi modifichi la Costituzione fregandotene del procedimento costituzionale da seguire, NON E&#8217; PIU&#8217; REATO !<\/p>\n<p>Infatti hanno anche introdotto la non perseguibilit\u00e0 del Presidente del Governo. Certo, mica si pu\u00f2 processare un terrorista eversore se mai lo si accertasse !<\/p>\n<p>Allora , diciamolo, la Costituzione non vale pi\u00f9 ! E&#8217; morta. Te ne puoi anche fregare, o meglio, solo loro.<br \/>\nIo in effetti avevo denunciato la sovversione delle istituzioni da parte di un gruppo organizzato che usava la mafia e la violenza per modificare la forma di governo.<\/p>\n<p>Ebbene, scopro oggi che perfino il reato di sovvertire le istituzioni \u00e8 stato abrogato, ossia dal 25 Gennaio 2006 non \u00e8 pi\u00f9 reato l&#8217;art. 272 del Codice Penale<\/p>\n<p><em>&#8220;Chiunque nel territorio dello Stato fa propaganda per la instaurazione violenta della dittatura di una classe sociale sulle altre, o per la soppressione violenta di una classe sociale o, comunque, per il sovvertimento violento degli ordinamenti economici o sociali costituiti nello Stato, ovvero fa propaganda per la distruzione di ogni ordinamento politico e giuridico della societ\u00e0, \u00e8 punito con la reclusione da uno a cinque anni. &#8221; <\/em><\/p>\n<p>\u00e8 stato sostituito con <em>&#8220;Chiunque commette un fatto diretto a mutare la costituzione dello Stato, o la forma del Governo, con mezzi non consentiti dall&#8217;ordinamento costituzionale dello Stato, \u00e8 punito con la reclusione non inferiore a dodici anni.<\/em>&#8221;<\/p>\n<p>Ora la mafia \u00e8 nel pieno della legalit\u00e0 e i comunisti e i fascisti possono fare un colpo di stato senza troppi scrupoli. Peccato che questi 2 ultimi non contini pi\u00f9 nulla .<\/p>\n<p>L&#8217;importante, secondo le nuove leggi, \u00e8 non dire che riconoscersi italiani \u00e8 da deficienti o parlare di razza inferiore. Cio\u00e9, l La Costituzione non vale pi\u00f9 una lenticchia, ma non si tocchi l&#8217;italianit\u00e0 !<\/p>\n<p style=\"margin-bottom: 0cm\"><a target=\"_blank\" href=\"http:\/\/www.lacostituzione.it\/altre_leggi\/opinioni.php \">http:\/\/www.lacostituzione.it\/altre_leggi\/opinioni.php <\/a><\/p>\n<p style=\"margin-bottom: 0cm\">\n","protected":false},"excerpt":{"rendered":"<p>Quale sarebbe la prima cosa che farebbe un gruppo terrorista e sovversivo che salisse al potere? Ovvio, quello che tutti i dittatori hanno sempre fatto, ossia: ABROGARE I REATI COMMESSI DA LORO STESSI. Sono molti anni che vado dicendo che c&#8217;\u00e8 stato un colpo di Stato in Italia, iniziato nel 1994, fatto da destra e [&hellip;]<\/p>\n","protected":false},"author":292,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-giustizia","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":4033,"url":"https:\/\/palmerini.net\/blog\/la-legge-naturale-non-e-una-legge\/","url_meta":{"origin":184,"position":0},"title":"LA LEGGE NATURALE NON E&#8217; UNA LEGGE","author":"Loris","date":"9 Dicembre 2015","format":false,"excerpt":"Negli ultimi anni si assiste alla diffusione di alcune teorie che vedono nella totale libert\u00e0 dell'individuo il valore supremo da difendere. Sono teorie che sostanzialmente fanno parte di quella corrente di pensiero che viene definita \"libertaria\" o anche anarchica. Infatti per la Treccani \"libertario\" \u00e8 chi o che \"considera e\u2026","rel":"","context":"In &quot;Attualit\u00e0\u00a0 e storia del Popolo Veneto&quot;","block_context":{"text":"Attualit\u00e0\u00a0 e storia del Popolo Veneto","link":"https:\/\/palmerini.net\/blog\/category\/autogoverno-popolo-veneto\/"},"img":{"alt_text":"YEAREND PICTURES 2000 - Ruqia Aroo, 80, carries her malnourished grandson Khalif Sheikh Adan, 5, near the carcasses of her dead herd of cattle near Afder, 1100 kms south east of Addis Ababa, April 18, 2000. (CANADA OUT) gm\/Photo by George Mulala REUTERS","src":"https:\/\/i0.wp.com\/www.palmerini.net\/blog\/wp-content\/uploads\/2015\/12\/eritrea-siccita-300x212.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":41060,"url":"https:\/\/palmerini.net\/blog\/come-il-pascolo-rigenerativo-combatte-il-cambiamento-climatico\/","url_meta":{"origin":184,"position":1},"title":"Come il pascolo rigenerativo combatte il cambiamento climatico","author":"Loris","date":"28 Luglio 2026","format":false,"excerpt":"L'Universit\u00e0 del Nebraska-Lincoln ha avviato un ampio progetto di ricerca (guidato, tra gli altri, dal professor Galen Erickson) per misurare le dinamiche tra vegetazione, suolo e bestiame. I ricercatori hanno evidenziato che valutare l'impatto climatico calcolando solo i gas emessi dagli animali restituisce un quadro parziale e fuorviante.Lo studio ha\u2026","rel":"","context":"In &quot;Alimentazione e Salute&quot;","block_context":{"text":"Alimentazione e Salute","link":"https:\/\/palmerini.net\/blog\/category\/alimentazione-e-salute\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/palmerini.net\/blog\/wp-content\/uploads\/2026\/07\/ciclo_pascolo.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/292"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}