{"id":15939,"date":"2018-07-14T15:47:03","date_gmt":"2018-07-14T14:47:03","guid":{"rendered":"http:\/\/www.palmerini.net\/blog\/?p=15939"},"modified":"2020-05-25T17:06:54","modified_gmt":"2020-05-25T16:06:54","slug":"i-veneti-ci-rimettono-ciascuno-5600-euro-allanno-dalla-culla-alla-tomba","status":"publish","type":"post","link":"https:\/\/palmerini.net\/blog\/i-veneti-ci-rimettono-ciascuno-5600-euro-allanno-dalla-culla-alla-tomba\/","title":{"rendered":"I Veneti ci rimettono ciascuno 5600 Euro all\u2019anno, dalla culla alla tomba"},"content":{"rendered":"<p>E\u2019 una somma incredibile: ogni persona residente in Veneto, dalla culla alla tomba, ogni anno versa all\u2019Italia 5600 euro del proprio tenore di vita, vale a dire 467 Euro al mese.<\/p>\n<p>In pratica il Veneto indipendente, cos\u00ec come tutto il Lombardo-Veneto che per la maggior parte \u00e8 etnicamente Veneto, potrebbe far vivere dignitosamente ogni disoccupato, ogni malato, avere servizi all\u2019avanguardia mondiale, curare l\u2019ambiente, gestire il turismo, ripulirsi dalle spazzature italiane nella chimica, nell\u2019edilizia, potrebbe controllare perfettamente il proprio territorio, e ne avanzerebbe per aiutare i meritevoli nel mondo.<\/p>\n<p>Questa cifra incredibile <a href=\"http:\/\/www.ilgiornale.it\/news\/politica\/carroccio-ha-gi-archiviato-lautonomia-fiscale-nord-1549913.html\" target=\"_blank\" rel=\"noopener\">viene riferita dal Giornale,<\/a> che suggerendo che l\u2019autonomia fiscale in Veneto non arriver\u00e0, riporta un esborso della regione verso l\u2019Italia di ben 28 miliardi di Euro l\u2019anno, correggendo cos\u00ec al rialzo il Presidente regionale Zaia che ha sempre parlato di 21 o 22 miliardi di Euro all\u2019anno.<\/p>\n<p>Dividendo i 28 miliardi di Euro per i cinque milioni di residenti, esce la somma di 467 euro mensili sborsati per far parte dell&#8217;Italia, ma le cifre reali sono sicuramente molto maggiori, perch\u00e9 i 28 miliardi non tengono conto per esempio dell\u2019IVA che sarebbero una ulteriore incredibile massa di miliardi da riutilizzare in proprio se le Venezie fossero indipendenti.<\/p>\n<p>E mancano dal conto le accise su energia, carburanti, acqua, servizi pubblici, che non vengono conteggiate nella tassazione ufficiale.<br \/>\nMancano ancora i bolli da pagare e i controlli asfissianti e costi ad\u00a0 ogni iniziativa imprenditoriale ed individaule, le enormi tasse e spese per la ingiusta macchina della giustizia, le multe pagate per far cassa dei Comuni a loro volta derubati e mai risarciti nemmeno della prima guerra mondiale.<br \/>\nSenza contare il costo economico derivante dalla inefficiente giustizia e dalla criminalit\u00e0 libera di agire,\u00a0 i danni dalla criminalit\u00e0 dell\u2019amministrazione, i danni alla salute derivanti dal sistema di governo italiano che non controlla adeguatamente nemmeno l&#8217;inquinamento dell&#8217;aria.<\/p>\n<p>In poche parole ogni Veneto, dalla culla alla tomba, pu\u00f2 tranquillamente ragionevolmente pensare di venir depredato ciascun mese di mille Euro al mese per il fatto di essere stato dichiarato \u201citaliano\u201d tramite il voto nel 1866 , voto che per primo ho dimostrato nel 2007 essere stato fatto dai soldati italiani e non dai cittadini del Lombardo-Veneto.<\/p>\n<p>Invece a quanto pare il sistema di plagio e di propaganda italiano, unito alla oppressione e persecuzione fiscale, le discriminazioni nell\u2019amministrazione pubblica e nei concorsi, e il sistema di repressione mafioso e terrorista che inspiegabilmente entra in azione al momento opportuno (ma sappiamo perch\u00e9) fa credere ai Veneti che essere italiani sia un vantaggio.<\/p>\n<p>Nel frattempo i Veneti vengono sostituiti con allogeni che godono pure di 1.050 euro di sostegno mensili proprio pagati dallo Stato Italiano.<\/p>\n<p>Ecco caro Veneto, la realt\u00e0 di sta prendendo a sberle, stare con l\u2019Italia significa finanziare con i propri soldi la propria distruzione e sostituzione.<\/p>\n<p>Benvenuti nella vera Italia.<\/p>\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-15939\" data-postid=\"15939\" class=\"themify_builder_content themify_builder_content-15939 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 una somma incredibile: ogni persona residente in Veneto, dalla culla alla tomba, ogni anno versa all\u2019Italia 5600 euro del proprio tenore di vita, vale a dire 467 Euro al mese. In pratica il Veneto indipendente, cos\u00ec come tutto il Lombardo-Veneto che per la maggior parte \u00e8 etnicamente Veneto, potrebbe far vivere dignitosamente ogni disoccupato, [&hellip;]<\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12,8,135,1,11],"tags":[],"class_list":["post-15939","post","type-post","status-publish","format-standard","hentry","category-autogoverno-popolo-veneto","category-economia","category-lombven","category-personale","category-venetie","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/15939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/comments?post=15939"}],"version-history":[{"count":0,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/posts\/15939\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/media?parent=15939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/categories?post=15939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmerini.net\/blog\/wp-json\/wp\/v2\/tags?post=15939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}